{"id":19080,"date":"2023-09-27T13:56:32","date_gmt":"2023-09-27T13:56:32","guid":{"rendered":"https:\/\/celebreeprod.wpengine.com\/ellicott-city-md\/?page_id=19080"},"modified":"2026-02-23T14:53:09","modified_gmt":"2026-02-23T14:53:09","slug":"meet-our-team","status":"publish","type":"page","link":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/meet-our-team\/","title":{"rendered":"Meet Our Team"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; next_background_color=&#8221;#ffffff&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.22.0&#8243; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0.64) 0%|rgba(0,0,0,0.64) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Lutherville.jpg&#8221; custom_margin=&#8221;||&#8221; custom_padding=&#8221;||&#8221; bottom_divider_style=&#8221;waves&#8221; bottom_divider_height=&#8221;2vw&#8221; bottom_divider_height_last_edited=&#8221;off|desktop&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_header title=&#8221;Meet Our Team&#8221; text_orientation=&#8221;center&#8221; button_one_text=&#8221;CONTACT US&#8221; button_one_url=&#8221;\/cross-creek-ranch-tx\/contact-us\/&#8221; content_max_width=&#8221;1000px&#8221; _builder_version=&#8221;4.22.2&#8243; title_font=&#8221;Fredoka One||||||||&#8221; title_font_size=&#8221;80px&#8221; title_line_height=&#8221;1.4em&#8221; content_font=&#8221;Muli||||||||&#8221; content_line_height=&#8221;1.8em&#8221; subhead_font=&#8221;|700|||||||&#8221; subhead_font_size=&#8221;30px&#8221; background_color=&#8221;rgba(126,190,197,0)&#8221; custom_button_one=&#8221;on&#8221; button_one_text_size=&#8221;16px&#8221; button_one_text_color=&#8221;#FFFFFF&#8221; button_one_bg_color=&#8221;#b5be02&#8243; button_one_border_width=&#8221;12px&#8221; button_one_border_color=&#8221;rgba(0,0,0,0)&#8221; button_one_border_radius=&#8221;50px&#8221; button_one_letter_spacing=&#8221;4px&#8221; button_one_font=&#8221;Fredoka One|||on|||||&#8221; button_one_use_icon=&#8221;off&#8221; custom_button_two=&#8221;on&#8221; button_two_text_size=&#8221;16px&#8221; button_two_text_color=&#8221;#ff236c&#8221; button_two_bg_color=&#8221;#ffffff&#8221; button_two_border_width=&#8221;12px&#8221; button_two_border_color=&#8221;#ffffff&#8221; button_two_border_radius=&#8221;50px&#8221; button_two_letter_spacing=&#8221;4px&#8221; button_two_font=&#8221;Fredoka One|900||on|||||&#8221; button_two_use_icon=&#8221;off&#8221; custom_margin=&#8221;||||false&#8221; custom_padding=&#8221;8vw||8vw||true|false&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;5%&#8221; title_font_size_tablet=&#8221;60px&#8221; title_font_size_phone=&#8221;40px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; content_font_size_tablet=&#8221;&#8221; content_font_size_phone=&#8221;16px&#8221; content_font_size_last_edited=&#8221;on|phone&#8221; subhead_font_size_tablet=&#8221;25px&#8221; subhead_font_size_phone=&#8221;25px&#8221; subhead_font_size_last_edited=&#8221;on|phone&#8221; custom_css_header_container=&#8221;width: 100%;&#8221; title_text_shadow_style=&#8221;preset1&#8243; title_text_shadow_blur_strength=&#8221;0.14em&#8221; title_text_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; box_shadow_style_button_one=&#8221;preset3&#8243; box_shadow_blur_button_one=&#8221;48px&#8221; button_one_letter_spacing_hover=&#8221;4px&#8221; button_two_letter_spacing_hover=&#8221;4px&#8221; global_colors_info=&#8221;{}&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;on&#8221; button_one_letter_spacing__hover=&#8221;4px&#8221; button_two_letter_spacing__hover_enabled=&#8221;on&#8221; button_two_letter_spacing__hover=&#8221;4px&#8221; button_one_bg_color__hover_enabled=&#8221;on|hover&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; background_color__hover=&#8221;#7EBEC5&#8243; background_color__hover_enabled=&#8221;#7EBEC5&#8243; use_background_color_gradient__hover=&#8221;off&#8221; use_background_color_gradient__hover_enabled=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;#2b87da&#8221; background_color_gradient_start__hover_enabled=&#8221;#2b87da&#8221; background_color_gradient_end__hover=&#8221;#29c4a9&#8243; background_color_gradient_end__hover_enabled=&#8221;#29c4a9&#8243; background_color_gradient_type__hover=&#8221;linear&#8221; background_color_gradient_type__hover_enabled=&#8221;linear&#8221; background_color_gradient_direction__hover=&#8221;180deg&#8221; background_color_gradient_direction__hover_enabled=&#8221;180deg&#8221; background_color_gradient_direction_radial__hover=&#8221;center&#8221; background_color_gradient_direction_radial__hover_enabled=&#8221;center&#8221; background_color_gradient_start_position__hover=&#8221;0%&#8221; background_color_gradient_start_position__hover_enabled=&#8221;0%&#8221; background_color_gradient_end_position__hover=&#8221;100%&#8221; background_color_gradient_end_position__hover_enabled=&#8221;100%&#8221; background_color_gradient_overlays_image__hover=&#8221;off&#8221; background_color_gradient_overlays_image__hover_enabled=&#8221;off&#8221; parallax__hover=&#8221;off&#8221; parallax__hover_enabled=&#8221;off&#8221; parallax_method__hover=&#8221;off&#8221; parallax_method__hover_enabled=&#8221;off&#8221; background_size__hover=&#8221;cover&#8221; background_size__hover_enabled=&#8221;cover&#8221; background_position__hover=&#8221;center&#8221; background_position__hover_enabled=&#8221;center&#8221; background_repeat__hover=&#8221;no-repeat&#8221; background_repeat__hover_enabled=&#8221;no-repeat&#8221; background_blend__hover=&#8221;normal&#8221; background_blend__hover_enabled=&#8221;normal&#8221; allow_player_pause__hover=&#8221;off&#8221; allow_player_pause__hover_enabled=&#8221;off&#8221; background_video_pause_outside_viewport__hover=&#8221;on&#8221; background_video_pause_outside_viewport__hover_enabled=&#8221;on&#8221; background_color_gradient_stops__hover=&#8221;#2b87da 0%|#29c4a9 100%&#8221; button_one_bg_color__hover=&#8221;#E09900&#8243;][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-content\/uploads\/sites\/86\/2025\/06\/Krishna-Kikani.jpg&#8221; alt=&#8221;Placeholder photo&#8221; title_text=&#8221;Krishna Kikani&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Krishna Kikani&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>School Owner\/Operator<br \/><span>\r\n\t<a class=\"paoc-pro-popup-cust-22734 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span><\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-content\/uploads\/sites\/86\/2025\/06\/Parth-Kikani.jpg&#8221; alt=&#8221;Placeholder photo&#8221; title_text=&#8221;Parth Kikani&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Parth Kikani&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>School Owner\/Operator<br \/><span>\r\n\t<a class=\"paoc-pro-popup-cust-22732 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span><\/p>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-content\/uploads\/sites\/86\/2026\/02\/Tara-Griffin.jpg&#8221; alt=&#8221;School Director of Cross Creek Ranch Tara Griffin&#8221; title_text=&#8221;Tara Griffin&#8221; force_fullwidth=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_cta title=&#8221;Tara Griffin&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>School Director<br \/><span>\r\n\t<a class=\"paoc-pro-popup-cust-22737 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span><\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Richie_Huffman.jpg&#8221; title_text=&#8221;Richie_Huffman&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Richie Huffman&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]President and CEO<br \/>\n\r\n\t<a class=\"paoc-pro-popup-cust-19189 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Allison_Tsomos.jpg&#8221; title_text=&#8221;Allison_Tsomos&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Allison Tsomos&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]Chief Operating Officer<br \/>\n<span>\r\n\t<a class=\"paoc-pro-popup-cust-19191 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Lisa_Bricker.jpg&#8221; title_text=&#8221;Lisa_Bricker&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Lisa Bricker&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]Chief Talent Officer<br \/>\n<span>\r\n\t<a class=\"paoc-pro-popup-cust-19193 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Emily_Samuels.jpg&#8221; title_text=&#8221;Emily_Samuels&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Emily Samuels&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]Director of Operations<br \/>\n<span>\r\n\t<a class=\"paoc-pro-popup-cust-19195 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Kristen_Miller.jpg&#8221; title_text=&#8221;Kristen_Miller&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Kristen Miller&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]Director of Education<br \/>\n<span>\r\n\t<a class=\"paoc-pro-popup-cust-19197 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/Stefanie-Shurer.jpg&#8221; title_text=&#8221;Stefanie-Shurer&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Stefanie Shurer&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]Director of Franchise Training<br \/>\n<span>\r\n\t<a class=\"paoc-pro-popup-cust-19198 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>District Directors<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/human-profile-silhouette-isolated-icon-vector-9813337.jpg&#8221; title_text=&#8221;human-profile-silhouette-isolated-icon-vector-9813337&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Susan Finger&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]District Director<br \/>\n<span>\r\n\t<a class=\"paoc-pro-popup-cust-21600 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\n<\/span>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/human-profile-silhouette-isolated-icon-vector-9813337.jpg&#8221; title_text=&#8221;human-profile-silhouette-isolated-icon-vector-9813337&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Tiffany Mills&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]District Director<br \/>\nBio to Come[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/human-profile-silhouette-isolated-icon-vector-9813337.jpg&#8221; title_text=&#8221;human-profile-silhouette-isolated-icon-vector-9813337&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Mariah Shifman&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]District Director<br \/>\nBio to Come[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/09\/human-profile-silhouette-isolated-icon-vector-9813337.jpg&#8221; title_text=&#8221;human-profile-silhouette-isolated-icon-vector-9813337&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_cta title=&#8221;Daria Ferrera&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;22px&#8221; background_color=&#8221;#0d3a5d&#8221; custom_padding=&#8221;20px|10px|0px|10px|false|true&#8221; border_radii=&#8221;off|||10px|10px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]District Director<br \/>\n<span>Bio to Come<\/span>[\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;||31px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_letter_spacing=&#8221;1px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"has-text-color\"><strong><em>Let\u2019s launch their lifelong love of learning together. Contact us to visit Celebree <span><span class=\"ui-provider pc bnj bgp cpe cpf cpg cph cpi cpj cpk cpl cpm cpn cpo cpp cpq cpr cps cpt cpu cpv cpw cpx cpy cpz cqa cqb cqc cqd cqe cqf cqg cqh cqi cqj\" dir=\"ltr\">School <\/span><\/span> of Cross Creek Ranch!<\/em><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;\/cross-creek-ranch-tx\/contact-us\/&#8221; button_text=&#8221;CONTACT US&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.22.2&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#b5be00&#8243; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;50px&#8221; button_letter_spacing=&#8221;4px&#8221; button_font=&#8221;Fredoka One|900||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;30px||40px||false|false&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;22px&#8221; box_shadow_blur=&#8221;64px&#8221; box_shadow_spread=&#8221;-18px&#8221; box_shadow_color=&#8221;rgba(92,42,131,0.45)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on|desktop&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221; button_bg_color__hover=&#8221;#f28b00&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#003a5d&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_module=&#8221;19239&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-content\/uploads\/sites\/86\/2023\/10\/NECPA-1.jpg&#8221; alt=&#8221;NECPA&#8221; title_text=&#8221;NECPA&#8221; url=&#8221;https:\/\/necpa.net\/page\/the-necpa-choice\/&#8221; url_new_window=&#8221;on&#8221; disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;footer-logo&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;200px&#8221; width_tablet=&#8221;200px&#8221; width_phone=&#8221;150px&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;|20px|20px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/10\/maryland_accreditation_horizontal_logo-1.png&#8221; alt=&#8221;Maryland Acceditation&#8221; title_text=&#8221;maryland_accreditation_horizontal_logo (1)&#8221; disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;footer-logo&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;200px&#8221; width_tablet=&#8221;200px&#8221; width_phone=&#8221;150px&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;|20px|20px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_menu menu_id=&#8221;396&#8243; disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;app-footer__menu&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; menu_font_size=&#8221;16px&#8221; menu_line_height=&#8221;26px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_margin=&#8221;||1em||false|false&#8221; custom_padding=&#8221;||23px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_menu][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_2,1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.celebree.com\/wp-content\/uploads\/sites\/86\/2023\/08\/celebree-logo.webp&#8221; title_text=&#8221;celebree-logo&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_orientation=&#8221;right&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<strong>Celebree School of Cross Creek Ranch <\/strong><br \/>\n6511 skyline drive<br \/>\nFulshear, TX, 77441<br \/>\n<a class=\"app-footer__info-phone\" style=\"color: #b5be00;font-weight: bold;font-size: 22px\" href=\"tel:346-615-0102\">346-615-0102<\/a>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>School Owner\/Operator\r\n\t<a class=\"paoc-pro-popup-cust-22734 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nSchool Owner\/Operator\r\n\t<a class=\"paoc-pro-popup-cust-22732 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nSchool Director\r\n\t<a class=\"paoc-pro-popup-cust-22737 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nPresident and CEO \r\n\t<a class=\"paoc-pro-popup-cust-19189 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nChief Operating Officer \r\n\t<a class=\"paoc-pro-popup-cust-19191 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nChief Talent Officer \r\n\t<a class=\"paoc-pro-popup-cust-19193 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nDirector of Operations \r\n\t<a class=\"paoc-pro-popup-cust-19195 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nDirector of Education \r\n\t<a class=\"paoc-pro-popup-cust-19197 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nDirector of Franchise Training \r\n\t<a class=\"paoc-pro-popup-cust-19198 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nDistrict DirectorsDistrict Director \r\n\t<a class=\"paoc-pro-popup-cust-21600 paoc-popup-click paoc-popup-simple_link  paoc-action-popup paoc-pro-popup-link\" href=\"javascript:void(0);\">Bio<\/a>\r\n\r\nDistrict Director Bio to ComeDistrict Director Bio to ComeDistrict Director Bio to ComeLet\u2019s launch their lifelong love of learning together. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-19080","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/pages\/19080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/comments?post=19080"}],"version-history":[{"count":5,"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/pages\/19080\/revisions"}],"predecessor-version":[{"id":22885,"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/pages\/19080\/revisions\/22885"}],"wp:attachment":[{"href":"https:\/\/www.celebree.com\/cross-creek-ranch-tx\/wp-json\/wp\/v2\/media?parent=19080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}